{"id":14114,"date":"2020-09-03T15:48:20","date_gmt":"2020-09-03T15:48:20","guid":{"rendered":"https:\/\/livunltd.com\/?p=14114"},"modified":"2026-04-15T20:08:39","modified_gmt":"2026-04-15T20:08:39","slug":"al-fresco-fitness","status":"publish","type":"post","link":"https:\/\/livunltd.com\/fr\/al-fresco-fitness\/","title":{"rendered":"Fitness en plein air : Les cours d'entra\u00eenement \u00e0 l'ext\u00e9rieur \u00e0 essayer"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1-1024x768.png\" alt=\"\" class=\"wp-image-14127\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Apr\u00e8s cinq mois, les gymnases de New York sont d\u00e9sormais autoris\u00e9s \u00e0 rouvrir, mais le fitness en groupe en salle n&#039;est pas (encore !) au programme. Nous sommes ici pour partager six de nos studios de fitness pr\u00e9f\u00e9r\u00e9s qui ont mis leurs programmes en ext\u00e9rieur. Parfait pour ceux qui ont rat\u00e9 l\u2019exp\u00e9rience d\u2019entra\u00eenement en groupe et juste \u00e0 temps pour profiter des derniers instants de chaleur estivale.<\/p>\n\n\n\n<p>Pr\u00eat \u00e0 participer ? Les billets et les r\u00e9servations peuvent \u00eatre organis\u00e9s aupr\u00e8s de votre concierge LIVunLtd, et vous pouvez nous envoyer votre demande via le <a aria-label=\"non d\u00e9fini (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/apps.apple.com\/us\/app\/livunltd\/id1322106008\" target=\"_blank\" rel=\"noreferrer noopener\">Application LIV<\/a>, <a aria-label=\"non d\u00e9fini (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/concierge.livunltd.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">notre portail web<\/a>ou par <a aria-label=\"non d\u00e9fini (s&#039;ouvre dans un nouvel onglet)\" href=\"mailto:concierge@livunltd.com\" target=\"_blank\" rel=\"noreferrer noopener\">l'envoi de courriels<\/a> ou <a href=\"call:2127842390\">ca<\/a><a aria-label=\"non d\u00e9fini (s&#039;ouvre dans un nouvel onglet)\" href=\"\/fr\/2127842390\/\" target=\"_blank\" rel=\"noreferrer noopener\">l<\/a><a href=\"call:2127842390\">Nous lions<\/a> directement.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/2-1024x768.png\" alt=\"\" class=\"wp-image-14117\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/2-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/2-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/2-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/2-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/2.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">BOX+FLOW et bodyART<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">Parc Vale au William Vale, Williamsburg<\/h6>\n\n\n\n<p>Les cours de signature par <a href=\"https:\/\/www.thewilliamvale.com\/culture\/box_flow\/\">Bo\u00eete + Flux<\/a> et <a href=\"https:\/\/www.thewilliamvale.com\/culture\/deepwork\/\">art corporel<\/a> J&#039;ai maintenant une r\u00e9sidence jusqu&#039;en septembre \u00e0 Vale Park qui propose un entra\u00eenement au mouvement bas\u00e9 sur la th\u00e9rapie, du shadow boxing, du HIIT et du vinyasa flow. La m\u00e9thode bodyART est rythm\u00e9e par une musique \u00e9tonnante et des rythmes deep house. Attendez-vous \u00e0 transpirer, \u00e0 vous \u00e9tirer et \u00e0 renforcer votre corps tout en pr\u00e9venant les blessures, en r\u00e9duisant les douleurs articulaires et en garantissant une sant\u00e9 durable \u00e0 long terme. Poids et tapis fournis. N&#039;h\u00e9sitez pas \u00e0 apporter votre propre tapis si vous pr\u00e9f\u00e9rez. Les directives de distance sociale seront suivies. N&#039;oubliez pas votre masque !  <\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group has-vivid-purple-color has-text-color\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/3-1024x768.png\" alt=\"\" class=\"wp-image-14118\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/3-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/3-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/3-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/3-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/3.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Yoga au bord de la piscine avec OneYogaHouse<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">La maison de plage de Montauk<\/h6>\n\n\n\n<p>Profitez du yoga en plein air avec <a href=\"https:\/\/oneyogahouse.com\/montauk-schedule\/\">OneYogaMaison<\/a> dans le spacieux salon au bord de la piscine du <a href=\"https:\/\/thembh.com\/\">Maison de plage de Montauk<\/a> jusqu&#039;en octobre. Une exp\u00e9rience de flux Vinyasa dynamique inspir\u00e9e de l&#039;Iyengar, intentionnelle, amusante et guid\u00e9e par le rythme de la respiration. Attendez-vous \u00e0 un flux rigoureux o\u00f9 les \u00e9tudiants sont mis au d\u00e9fi \u00e0 la fois physiquement et mentalement, beaucoup de mouvement et transpirent. BYO Mat ou louez-en un sur place\u00a0!<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/4-1024x768.png\" alt=\"\" class=\"wp-image-14119\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/4-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/4-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/4-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/4-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/4.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">SoulOutside avec SoulCycle<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">Cour arri\u00e8re \u00e0 Hudson Yards, Montauk, Bridgehampton, Water Mill et Southampton !<\/h6>\n\n\n\n<p>Rendez-vous \u00e0 Hudson Yards pour profiter du <a href=\"https:\/\/www.hudsonyardsnewyork.com\/events\/backyard-hudson-yards\">Cour arri\u00e8re \u00e0 Hudson Yards<\/a> avec des boissons de saison, des repas en plein air, des s\u00e9ances d&#039;entra\u00eenement en plein air et des activit\u00e9s familiales sur la place publique et les jardins. SoulCycle et Equinox organisent des cours de fitness en groupe juste \u00e0 c\u00f4t\u00e9 du navire. Si vous \u00eates dans l&#039;Est, profitez de l&#039;un de leurs emplacements dans les Hamptons\u00a0!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/5-1024x768.png\" alt=\"\" class=\"wp-image-14120\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/5-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/5-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/5-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/5-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/5.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les falaises de DUMBO<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">DUMBO, Brooklyn<\/h6>\n\n\n\n<p><a href=\"https:\/\/dumbo.thecliffsclimbing.com\/\">Les falaises de DUMBO<\/a> propose du bloc, un type d&#039;escalade ax\u00e9 sur le mouvement et ne n\u00e9cessitant aucune exp\u00e9rience, corde ou partenaire. R\u00e9servez un cr\u00e9neau de deux heures \u00e0 l&#039;avance et n&#039;oubliez pas votre masque. Rock On!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/6-1-1024x768.png\" alt=\"\" class=\"wp-image-14121\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/6-1-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/6-1-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/6-1-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/6-1-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/6-1.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Yoga en position inclin\u00e9e avec le mus\u00e9e de Brooklyn<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">Prospect Heights, Brooklyn<\/h6>\n\n\n\n<p>Profitez d&#039;une matin\u00e9e de yoga et de m\u00e9ditation \u00e0 distance sur les marches du Brooklyn Museum. Les cours se concentrent sur des techniques douces d\u2019ouverture du c\u0153ur pour se reconnecter \u00e0 sa respiration, encourager la joie et inciter \u00e0 de nouveaux d\u00e9parts. Les masques sont obligatoires pour tous les adultes et les enfants de plus de 2 ans. Les billets incluent l&#039;entr\u00e9e g\u00e9n\u00e9rale au mus\u00e9e afin que vous puissiez explorer apr\u00e8s le flux. Apportez votre propre tapis \u00e0 celui-ci\u00a0! <\/p>\n\n\n\n<p>Samedi 19 septembre de 10h \u00e0 11h<br>Samedi 26 septembre de 10h \u00e0 11h<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/livunltd.comwp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1024x768.png\" alt=\"\" class=\"wp-image-14125\" srcset=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1024x768.png 1024w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-300x225.png 300w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-768x576.png 768w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images-1536x1152.png 1536w, https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/LIVELY-Blog-_-Al-Fresco-Fitness-Images.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Stand-Up Paddleboard Elements Fitness<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">Hampton Est<\/h6>\n\n\n\n<p><a href=\"https:\/\/elementsfitnessstudio.com\/\">\u00c9l\u00e9ments de remise en forme<\/a> a int\u00e9gr\u00e9 ses exercices de barre aux techniques de stand-up paddleboard. Les cours ont tous lieu \u00e0 l&#039;ext\u00e9rieur le samedi, avec des planches et des pagaies d\u00e9sinfect\u00e9es fournies. Vous pouvez \u00e9galement les rejoindre pour des cours et des excursions personnels de SUP \u2013 parfait pour un petit rassemblement !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><a aria-label=\"non d\u00e9fini (s&#039;ouvre dans un nouvel onglet)\" href=\"mailto:concierge@livunltd.com\" target=\"_blank\" rel=\"noreferrer noopener\">Contact your concierge to book!<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s cinq mois, les gymnases de New York sont d\u00e9sormais autoris\u00e9s \u00e0 rouvrir, mais le fitness en groupe en salle n&#039;est pas (encore !) au programme. Nous sommes ici pour partager six de nos studios de fitness pr\u00e9f\u00e9r\u00e9s qui ont mis leurs programmes en ext\u00e9rieur. Parfait pour ceux qui\u2026<\/p>","protected":false},"author":2,"featured_media":14123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,51],"tags":[],"class_list":["post-14114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-wellness"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al Fresco Fitness: The Outside Workout Classes to Try - LIVunLtd<\/title>\n<meta name=\"description\" content=\"In order to bring more attention and support to the contributions of BIPOC in the lifestyle category, we&#039;re highlighting some of our favorite Black business owners, designers, and culinary geniuses. Put your purchasing power to good use!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livunltd.com\/fr\/al-fresco-fitness\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al Fresco Fitness: The Outside Workout Classes to Try - LIVunLtd\" \/>\n<meta property=\"og:description\" content=\"In order to bring more attention and support to the contributions of BIPOC in the lifestyle category, we&#039;re highlighting some of our favorite Black business owners, designers, and culinary geniuses. Put your purchasing power to good use!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livunltd.com\/fr\/al-fresco-fitness\/\" \/>\n<meta property=\"og:site_name\" content=\"LIVunLtd\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-03T15:48:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T20:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-09-02-at-5.44.57-PM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1194\" \/>\n\t<meta property=\"og:image:height\" content=\"838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eva Eckstein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eva Eckstein\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/\"},\"author\":{\"name\":\"Eva Eckstein\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/#\\\/schema\\\/person\\\/7277cad3f38ba4f4f488b2000b95a94a\"},\"headline\":\"Al Fresco Fitness: The Outside Workout Classes to Try\",\"datePublished\":\"2020-09-03T15:48:20+00:00\",\"dateModified\":\"2026-04-15T20:08:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/\"},\"wordCount\":523,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/livunltd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Screen-Shot-2020-09-02-at-5.44.57-PM.png\",\"articleSection\":[\"Featured\",\"WELLNESS\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/\",\"url\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/\",\"name\":\"Al Fresco Fitness: The Outside Workout Classes to Try - LIVunLtd\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/livunltd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Screen-Shot-2020-09-02-at-5.44.57-PM.png\",\"datePublished\":\"2020-09-03T15:48:20+00:00\",\"dateModified\":\"2026-04-15T20:08:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/#\\\/schema\\\/person\\\/7277cad3f38ba4f4f488b2000b95a94a\"},\"description\":\"In order to bring more attention and support to the contributions of BIPOC in the lifestyle category, we're highlighting some of our favorite Black business owners, designers, and culinary geniuses. Put your purchasing power to good use!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#primaryimage\",\"url\":\"https:\\\/\\\/livunltd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Screen-Shot-2020-09-02-at-5.44.57-PM.png\",\"contentUrl\":\"https:\\\/\\\/livunltd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Screen-Shot-2020-09-02-at-5.44.57-PM.png\",\"width\":1194,\"height\":838},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/al-fresco-fitness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/livunltd.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al Fresco Fitness: The Outside Workout Classes to Try\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/#website\",\"url\":\"https:\\\/\\\/livunltd.com\\\/\",\"name\":\"LIVunLtd\",\"description\":\"Concierge, Fitness &amp; Wellness Services\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livunltd.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/livunltd.com\\\/#\\\/schema\\\/person\\\/7277cad3f38ba4f4f488b2000b95a94a\",\"name\":\"Eva Eckstein\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99bd19402dac753fda3453b48fe55863d9e5cc840781ab96526140a580fdd3d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99bd19402dac753fda3453b48fe55863d9e5cc840781ab96526140a580fdd3d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99bd19402dac753fda3453b48fe55863d9e5cc840781ab96526140a580fdd3d8?s=96&d=mm&r=g\",\"caption\":\"Eva Eckstein\"},\"url\":\"https:\\\/\\\/livunltd.com\\\/fr\\\/author\\\/rachel-w\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fitness en plein air\u00a0: les cours d&#039;entra\u00eenement en ext\u00e9rieur \u00e0 essayer - LIVunLtd","description":"Afin d&#039;attirer l&#039;attention et de soutenir davantage les contributions des personnes noires, autochtones et de couleur (BIPOC) dans le domaine du style de vie, nous mettons en lumi\u00e8re certains de nos entrepreneurs, designers et g\u00e9nies culinaires noirs pr\u00e9f\u00e9r\u00e9s. Faites bon usage de votre pouvoir d&#039;achat\u00a0!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livunltd.com\/fr\/al-fresco-fitness\/","og_locale":"fr_CA","og_type":"article","og_title":"Al Fresco Fitness: The Outside Workout Classes to Try - LIVunLtd","og_description":"In order to bring more attention and support to the contributions of BIPOC in the lifestyle category, we're highlighting some of our favorite Black business owners, designers, and culinary geniuses. Put your purchasing power to good use!","og_url":"https:\/\/livunltd.com\/fr\/al-fresco-fitness\/","og_site_name":"LIVunLtd","article_published_time":"2020-09-03T15:48:20+00:00","article_modified_time":"2026-04-15T20:08:39+00:00","og_image":[{"width":1194,"height":838,"url":"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-09-02-at-5.44.57-PM.png","type":"image\/png"}],"author":"Eva Eckstein","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Eva Eckstein","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#article","isPartOf":{"@id":"https:\/\/livunltd.com\/al-fresco-fitness\/"},"author":{"name":"Eva Eckstein","@id":"https:\/\/livunltd.com\/#\/schema\/person\/7277cad3f38ba4f4f488b2000b95a94a"},"headline":"Al Fresco Fitness: The Outside Workout Classes to Try","datePublished":"2020-09-03T15:48:20+00:00","dateModified":"2026-04-15T20:08:39+00:00","mainEntityOfPage":{"@id":"https:\/\/livunltd.com\/al-fresco-fitness\/"},"wordCount":523,"commentCount":0,"image":{"@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#primaryimage"},"thumbnailUrl":"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-09-02-at-5.44.57-PM.png","articleSection":["Featured","WELLNESS"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/livunltd.com\/al-fresco-fitness\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/livunltd.com\/al-fresco-fitness\/","url":"https:\/\/livunltd.com\/al-fresco-fitness\/","name":"Fitness en plein air\u00a0: les cours d&#039;entra\u00eenement en ext\u00e9rieur \u00e0 essayer - LIVunLtd","isPartOf":{"@id":"https:\/\/livunltd.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#primaryimage"},"image":{"@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#primaryimage"},"thumbnailUrl":"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-09-02-at-5.44.57-PM.png","datePublished":"2020-09-03T15:48:20+00:00","dateModified":"2026-04-15T20:08:39+00:00","author":{"@id":"https:\/\/livunltd.com\/#\/schema\/person\/7277cad3f38ba4f4f488b2000b95a94a"},"description":"Afin d&#039;attirer l&#039;attention et de soutenir davantage les contributions des personnes noires, autochtones et de couleur (BIPOC) dans le domaine du style de vie, nous mettons en lumi\u00e8re certains de nos entrepreneurs, designers et g\u00e9nies culinaires noirs pr\u00e9f\u00e9r\u00e9s. Faites bon usage de votre pouvoir d&#039;achat\u00a0!","breadcrumb":{"@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livunltd.com\/al-fresco-fitness\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#primaryimage","url":"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-09-02-at-5.44.57-PM.png","contentUrl":"https:\/\/livunltd.com\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-09-02-at-5.44.57-PM.png","width":1194,"height":838},{"@type":"BreadcrumbList","@id":"https:\/\/livunltd.com\/al-fresco-fitness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/livunltd.com\/"},{"@type":"ListItem","position":2,"name":"Al Fresco Fitness: The Outside Workout Classes to Try"}]},{"@type":"WebSite","@id":"https:\/\/livunltd.com\/#website","url":"https:\/\/livunltd.com\/","name":"LIVunLtd","description":"Services de conciergerie, de remise en forme et de bien-\u00eatre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livunltd.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/livunltd.com\/#\/schema\/person\/7277cad3f38ba4f4f488b2000b95a94a","name":"Eva Eckstein","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/99bd19402dac753fda3453b48fe55863d9e5cc840781ab96526140a580fdd3d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99bd19402dac753fda3453b48fe55863d9e5cc840781ab96526140a580fdd3d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99bd19402dac753fda3453b48fe55863d9e5cc840781ab96526140a580fdd3d8?s=96&d=mm&r=g","caption":"Eva Eckstein"},"url":"https:\/\/livunltd.com\/fr\/author\/rachel-w\/"}]}},"_links":{"self":[{"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/posts\/14114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/comments?post=14114"}],"version-history":[{"count":0,"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/posts\/14114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/media\/14123"}],"wp:attachment":[{"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/media?parent=14114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/categories?post=14114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livunltd.com\/fr\/wp-json\/wp\/v2\/tags?post=14114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}